{"id":175,"count":1,"description":"","link":"https:\/\/amalie-von-stein.com\/en\/category\/bdsm-toys\/keuschheitskaefig\/","name":"penis cage","slug":"keuschheitskaefig","taxonomy":"category","parent":133,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Keuschheitsk\u00e4fig Archive - Amalie von Stein<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keuschheitsk\u00e4fig Archive - Amalie von Stein\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amalie-von-stein.com\/en\/category\/bdsm-toys\/keuschheitskaefig\/\" \/>\n<meta property=\"og:site_name\" content=\"Amalie von Stein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/amalie-von-stein-dominatrix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmalievonStein\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/category\\\/bdsm-toys\\\/keuschheitskaefig\\\/\",\"url\":\"https:\\\/\\\/amalie-von-stein.com\\\/category\\\/bdsm-toys\\\/keuschheitskaefig\\\/\",\"name\":\"Keuschheitsk\u00e4fig Archive - Amalie von Stein\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/category\\\/bdsm-toys\\\/keuschheitskaefig\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/category\\\/bdsm-toys\\\/keuschheitskaefig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/amalie-von-stein.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BDSM Toys\",\"item\":\"https:\\\/\\\/amalie-von-stein.com\\\/category\\\/bdsm-toys\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Keuschheitsk\u00e4fig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/#website\",\"url\":\"https:\\\/\\\/amalie-von-stein.com\\\/\",\"name\":\"Amalie von Stein\",\"description\":\"Amalie von Stein: High Class Domina und Femdom Escort f\u00fcr den devoten Gentleman.\",\"publisher\":{\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/#\\\/schema\\\/person\\\/aa299bddf886d0b9d5dfa855dd6f7c15\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amalie-von-stein.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/#\\\/schema\\\/person\\\/aa299bddf886d0b9d5dfa855dd6f7c15\",\"name\":\"Femdom Amalie von Stein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/kontakt-exklusiver-domina-fetisch-escort-service.jpg\",\"url\":\"https:\\\/\\\/amalie-von-stein.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/kontakt-exklusiver-domina-fetisch-escort-service.jpg\",\"contentUrl\":\"https:\\\/\\\/amalie-von-stein.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/kontakt-exklusiver-domina-fetisch-escort-service.jpg\",\"width\":1280,\"height\":1920,\"caption\":\"Femdom Amalie von Stein\"},\"logo\":{\"@id\":\"https:\\\/\\\/amalie-von-stein.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/kontakt-exklusiver-domina-fetisch-escort-service.jpg\"},\"description\":\"Amalie von Stein ist eine klassische deutsche Domina und Fetisch Escort Mistress. Als elegante High Class Domina und Fetisch Escort Mistress f\u00fcr den devoten Sklaven und Fetisch Liebhaber bietet Amalie von Stein BDSM Sessions im Hotelzimmer oder im BDSM Studio an.\",\"sameAs\":[\"http:\\\/\\\/www.amalie-von-stein.com\",\"https:\\\/\\\/www.facebook.com\\\/amalievon.stein.37\",\"https:\\\/\\\/www.instagram.com\\\/amalie_von_stein\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/amalievonstein\\\/\",\"https:\\\/\\\/x.com\\\/AmalievonStein\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/swtone1\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Keuschheitsk\u00e4fig Archive - Amalie von Stein","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Keuschheitsk\u00e4fig Archive - Amalie von Stein","og_url":"https:\/\/amalie-von-stein.com\/en\/category\/bdsm-toys\/keuschheitskaefig\/","og_site_name":"Amalie von Stein","og_image":[{"width":1920,"height":1080,"url":"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/amalie-von-stein-dominatrix.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmalievonStein","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/amalie-von-stein.com\/category\/bdsm-toys\/keuschheitskaefig\/","url":"https:\/\/amalie-von-stein.com\/category\/bdsm-toys\/keuschheitskaefig\/","name":"Keuschheitsk\u00e4fig Archive - Amalie von Stein","isPartOf":{"@id":"https:\/\/amalie-von-stein.com\/#website"},"breadcrumb":{"@id":"https:\/\/amalie-von-stein.com\/category\/bdsm-toys\/keuschheitskaefig\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/amalie-von-stein.com\/category\/bdsm-toys\/keuschheitskaefig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/amalie-von-stein.com\/"},{"@type":"ListItem","position":2,"name":"BDSM Toys","item":"https:\/\/amalie-von-stein.com\/category\/bdsm-toys\/"},{"@type":"ListItem","position":3,"name":"Keuschheitsk\u00e4fig"}]},{"@type":"WebSite","@id":"https:\/\/amalie-von-stein.com\/#website","url":"https:\/\/amalie-von-stein.com\/","name":"Amalie von Stein","description":"Amalie von Stein: High Class Domina und Femdom Escort f\u00fcr den devoten Gentleman.","publisher":{"@id":"https:\/\/amalie-von-stein.com\/#\/schema\/person\/aa299bddf886d0b9d5dfa855dd6f7c15"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amalie-von-stein.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/amalie-von-stein.com\/#\/schema\/person\/aa299bddf886d0b9d5dfa855dd6f7c15","name":"Femdom Amalie von Stein","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/kontakt-exklusiver-domina-fetisch-escort-service.jpg","url":"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/kontakt-exklusiver-domina-fetisch-escort-service.jpg","contentUrl":"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/kontakt-exklusiver-domina-fetisch-escort-service.jpg","width":1280,"height":1920,"caption":"Femdom Amalie von Stein"},"logo":{"@id":"https:\/\/amalie-von-stein.com\/wp-content\/uploads\/2023\/04\/kontakt-exklusiver-domina-fetisch-escort-service.jpg"},"description":"Amalie von Stein ist eine klassische deutsche Domina und Fetisch Escort Mistress. Als elegante High Class Domina und Fetisch Escort Mistress f\u00fcr den devoten Sklaven und Fetisch Liebhaber bietet Amalie von Stein BDSM Sessions im Hotelzimmer oder im BDSM Studio an.","sameAs":["http:\/\/www.amalie-von-stein.com","https:\/\/www.facebook.com\/amalievon.stein.37","https:\/\/www.instagram.com\/amalie_von_stein\/","https:\/\/www.pinterest.de\/amalievonstein\/","https:\/\/x.com\/AmalievonStein","https:\/\/www.youtube.com\/user\/swtone1"]}]}},"_links":{"self":[{"href":"https:\/\/amalie-von-stein.com\/en\/wp-json\/wp\/v2\/categories\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amalie-von-stein.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/amalie-von-stein.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/amalie-von-stein.com\/en\/wp-json\/wp\/v2\/categories\/133"}],"wp:post_type":[{"href":"https:\/\/amalie-von-stein.com\/en\/wp-json\/wp\/v2\/posts?categories=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}